{"id":62137,"date":"2026-05-10T15:18:29","date_gmt":"2026-05-10T15:18:29","guid":{"rendered":"https:\/\/easyflighttraining.com\/?post_type=product&#038;p=62137"},"modified":"2026-05-10T15:28:55","modified_gmt":"2026-05-10T15:28:55","slug":"ask-a-pilot","status":"publish","type":"product","link":"https:\/\/easyflighttraining.com\/de\/product\/ask-a-pilot\/","title":{"rendered":"Frag einen Piloten"},"content":{"rendered":"<p>Du denkst dar\u00fcber nach, Pilot zu werden \u2013 m\u00f6chtest aber wissen, wie der Job wirklich aussieht?<\/p>\n<p>In dieser Live-Session gibt ein Pilot ehrliche Einblicke in den Alltag im Cockpit, die Ausbildung, den Lebensstil, die Verantwortung, den Druck, die Dienstpl\u00e4ne und die Dynamik innerhalb der Crew.<\/p>\n<p>Du wirst erfahren, was einen starken Piloten im realen Einsatz ausmacht und warum Kompetenzen wie Kommunikation, Entscheidungsfindung, Arbeitsbelastungsmanagement, Belastbarkeit, Bescheidenheit und die Chemie im Team schon von Beginn deiner Luftfahrtkarriere an wichtig sind.<\/p>\n<p>In dieser Veranstaltung werden diese Themen zudem mit den Auswahlverfahren der Fluggesellschaften verkn\u00fcpft, sodass du besser verstehst, worauf Arbeitgeber Wert legen \u2013 und warum viele Bewerber scheitern.<\/p>\n<p>Ein moderiertes AMA gibt dir die M\u00f6glichkeit, eigene Fragen zu stellen und dir ein realistisches Bild zu machen, bevor du den n\u00e4chsten Schritt machst.<\/p>","protected":false},"excerpt":{"rendered":"<ul>\n<li>Ehrliche Einblicke ins Cockpit<\/li>\n<li>Live-Frage-und-Antwort-Runde mit einem Piloten<\/li>\n<li>Auswahlkompetenzen erkl\u00e4rt<\/li>\n<li>F\u00fcr angehende Piloten<\/li>\n<\/ul>","protected":false},"featured_media":62140,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[591,27],"product_tag":[],"class_list":{"0":"post-62137","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-courses","7":"product_cat-application-preparation","9":"first","10":"instock","11":"virtual","12":"sold-individually","13":"purchasable","14":"product-type-booking"},"booking_location":"","booking_location_type":"","booking_duration":2,"booking_duration_unit":"hour","booking_buffer":0,"booking_cost":0,"booking_resources":[62138],"acf":[],"_links":{"self":[{"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/product\/62137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/comments?post=62137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/media\/62140"}],"wp:attachment":[{"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/media?parent=62137"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/product_brand?post=62137"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/product_cat?post=62137"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/easyflighttraining.com\/de\/wp-json\/wp\/v2\/product_tag?post=62137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}